{"id":69,"date":"2019-01-14T12:34:16","date_gmt":"2019-01-14T12:34:16","guid":{"rendered":"https:\/\/research.kent.ac.uk\/upgrade-statistics-research\/?page_id=69"},"modified":"2021-06-11T16:21:51","modified_gmt":"2021-06-11T15:21:51","slug":"current-research-projects","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/statistics\/current-research-projects\/","title":{"rendered":"Current research projects"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-69","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/pages\/69\/revisions\/1137"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/statistics\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}