{"id":734,"date":"2023-03-17T12:25:05","date_gmt":"2023-03-17T12:25:05","guid":{"rendered":"https:\/\/research.kent.ac.uk\/rural-homelessness\/?page_id=734"},"modified":"2023-03-23T09:25:58","modified_gmt":"2023-03-23T09:25:58","slug":"final-report","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/rural-homelessness\/home\/final-report\/","title":{"rendered":"Final Report"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1416,"featured_media":0,"parent":12,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-734","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/pages\/734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/users\/1416"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/comments?post=734"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/pages\/734\/revisions"}],"predecessor-version":[{"id":803,"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/pages\/734\/revisions\/803"}],"up":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/rural-homelessness\/wp-json\/wp\/v2\/media?parent=734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}