{"id":41,"date":"2019-01-15T10:56:23","date_gmt":"2019-01-15T10:56:23","guid":{"rendered":"https:\/\/research.kent.ac.uk\/upgrade-mathematics-research\/?page_id=41"},"modified":"2020-05-18T17:41:34","modified_gmt":"2020-05-18T16:41:34","slug":"mathematical-physics-and-nonlinear-systems","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/mathematics\/research\/mathematical-physics-and-nonlinear-systems\/","title":{"rendered":"Mathematical physics and nonlinear systems"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":128,"featured_media":0,"parent":24,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-41","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/pages\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/pages\/41\/revisions"}],"predecessor-version":[{"id":709,"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/pages\/41\/revisions\/709"}],"up":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/pages\/24"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/mathematics\/wp-json\/wp\/v2\/media?parent=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}