{"id":5507,"date":"2020-05-26T16:51:10","date_gmt":"2020-05-26T15:51:10","guid":{"rendered":"https:\/\/research.kent.ac.uk\/upgrade-gcrf-compass\/?page_id=5507"},"modified":"2023-01-03T12:44:14","modified_gmt":"2023-01-03T12:44:14","slug":"navroz-2019-roundtable-and-cultural-evening-8-march-2019-cambridge","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/gcrf-compass\/photo-galleries\/navroz-2019-roundtable-and-cultural-evening-8-march-2019-cambridge\/","title":{"rendered":"Navroz 2019 Roundtable and Cultural Evening, 8 March 2019, Cambridge"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":826,"featured_media":0,"parent":5449,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5507","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/users\/826"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/comments?post=5507"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5507\/revisions"}],"predecessor-version":[{"id":10113,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5507\/revisions\/10113"}],"up":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5449"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/media?parent=5507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}