{"id":5503,"date":"2020-05-26T16:49:06","date_gmt":"2020-05-26T15:49:06","guid":{"rendered":"https:\/\/research.kent.ac.uk\/upgrade-gcrf-compass\/?page_id=5503"},"modified":"2023-01-03T12:44:57","modified_gmt":"2023-01-03T12:44:57","slug":"uwed-conference-7-8-november-2019","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/gcrf-compass\/photo-galleries\/uwed-conference-7-8-november-2019\/","title":{"rendered":"UWED Conference 7-8 November 2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":826,"featured_media":0,"parent":5449,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5503","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/users\/826"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/comments?post=5503"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5503\/revisions"}],"predecessor-version":[{"id":10119,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5503\/revisions\/10119"}],"up":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5449"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/media?parent=5503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}