{"id":5459,"date":"2020-05-26T11:46:45","date_gmt":"2020-05-26T10:46:45","guid":{"rendered":"https:\/\/research.kent.ac.uk\/upgrade-gcrf-compass\/?page_id=5459"},"modified":"2023-01-03T12:46:41","modified_gmt":"2023-01-03T12:46:41","slug":"rainbow-gallery","status":"publish","type":"page","link":"https:\/\/research.kent.ac.uk\/gcrf-compass\/photo-galleries\/rainbow-gallery\/","title":{"rendered":"Rainbow Gallery"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":826,"featured_media":0,"parent":5449,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5459","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/users\/826"}],"replies":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/comments?post=5459"}],"version-history":[{"count":2,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5459\/revisions"}],"predecessor-version":[{"id":10137,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5459\/revisions\/10137"}],"up":[{"embeddable":true,"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/pages\/5449"}],"wp:attachment":[{"href":"https:\/\/research.kent.ac.uk\/gcrf-compass\/wp-json\/wp\/v2\/media?parent=5459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}